{"id":3109,"date":"2021-03-08T13:18:46","date_gmt":"2021-03-08T13:18:46","guid":{"rendered":"https:\/\/www.arataumodular.com\/app\/?page_id=3109"},"modified":"2025-05-21T12:46:00","modified_gmt":"2025-05-21T15:46:00","slug":"acerca-de","status":"publish","type":"page","link":"https:\/\/www.arataumodular.com\/app\/acerca-de\/","title":{"rendered":"Acerca de"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3109\" class=\"elementor elementor-3109\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c89838d elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7c89838d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-51ad86fa aux-appear-watch-animation aux-fade-in-right\" data-id=\"51ad86fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65ae90d0 elementor-widget elementor-widget-aux_modern_heading\" data-id=\"65ae90d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">Acerca de<\/h2><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b41f70 elementor-widget elementor-widget-aux_breadcrumbs\" data-id=\"8b41f70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"aux-elementor-breadcrumbs\"><p class=\"aux-breadcrumbs\"><span><span><a href=\"https:\/\/www.arataumodular.com\/app\/\">In\u00edcio<\/a><\/span><\/span><\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca2a472 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca2a472\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ce959dd\" data-id=\"2ce959dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49d9de1 aux-appear-watch-animation aux-fade-in-up elementor-widget elementor-widget-aux_modern_heading\" data-id=\"49d9de1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\"><\/h2><h3 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-before\">Conoce la historia de ARATAU<\/span><\/h3><div class=\"aux-modern-heading-divider\"><\/div><div class=\"aux-modern-heading-description\"><p>ARATAU - Construcci\u00f3n Modular es una empresa joven, pero nace con una enorme experiencia, sumando capacidades multidisciplinares en el sector de ingenier\u00eda, construcci\u00f3n e incorporaci\u00f3n de sus socios que tras m\u00e1s de 30 a\u00f1os:<\/p><p>- interfiriendo en la forma de dise\u00f1ar, planificar y construir;<\/p><p>- Introduciendo nuevas tecnolog\u00edas, procesos, productos y sistemas constructivos;<\/p><p>- Agotados y no satisfechos con la alta tasa de desperdicio, baja calidad y productividad, incertidumbres y doble trabajo, retrasos frecuentes y mayores costos de construcci\u00f3n;<\/p><p>- Y sin pasi\u00f3n por \"amontonar ladrillos\" o \"artesan\u00eda constructiva\" ...<\/p><p>\u2026 Decidieron actuar como agentes de cambio, creando ARATAU Construcci\u00f3n Modular, para llevar la industria de la construcci\u00f3n a otro nivel.<\/p><p>ARATAU es, con mucho orgullo, una empresa brasile\u00f1a, de est\u00e1ndar mundial. Naci\u00f3 en 2019, con un prop\u00f3sito fuerte, con seguridad y el compromiso de ofrecer a sus clientes una experiencia \u00fanica, contribuyendo a la mejora de la calidad de vida, sostenibilidad y entorno construido.<\/p><\/div><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d8d0f19 aux-appear-watch-animation aux-scale-down\" data-id=\"1d8d0f19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d5cedba elementor-widget elementor-widget-aux_image\" data-id=\"2d5cedba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au8162f823\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img fetchpriority=\"high\" decoding=\"async\" width=\"784\" height=\"700\" src=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/modulares-784x700.jpg\" class=\"aux-attachment aux-featured-image aux-attachment-id-1368 aux-img-dynamic-dropshadow\" alt=\"modulares\" srcset=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/modulares-150x134.jpg 150w,https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/modulares-300x268.jpg 300w,https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/modulares-768x686.jpg 768w,https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/modulares-1024x914.jpg 1024w,https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/modulares-784x700.jpg 784w\" data-ratio=\"1.12\" data-original-w=\"1561\" sizes=\"(max-width:479px) 480px,(max-width:767px) 768px,(max-width:1023px) 1024px,784px\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de14f3c elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de14f3c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-76ada92\" data-id=\"76ada92\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7d90dc elementor-widget elementor-widget-heading\" data-id=\"a7d90dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Misi\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdc277b elementor-widget elementor-widget-text-editor\" data-id=\"fdc277b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Brindar una experiencia \u00fanica en el recorrido del cliente, materializando sus sue\u00f1os a trav\u00e9s de la tecnolog\u00eda e innovaci\u00f3n en Construcci\u00f3n Modular, asegurando la predictibilidad de costos y plazos y total transparencia en el seguimiento de los proyectos por parte de los clientes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b9fd708\" data-id=\"b9fd708\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-009a718 elementor-widget elementor-widget-image\" data-id=\"009a718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2020\/12\/Missao.svg\" class=\"attachment-large size-large wp-image-144\" alt=\"\" srcset=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Missao.svg 150w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Missao.svg 300w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Missao.svg 768w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Missao.svg 1024w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Missao.svg 450w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-462a64c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"462a64c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-981da08\" data-id=\"981da08\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b00eb0b elementor-widget elementor-widget-image\" data-id=\"b00eb0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2020\/12\/Visao.svg\" class=\"attachment-large size-large wp-image-136\" alt=\"\" srcset=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Visao.svg 150w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Visao.svg 300w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Visao.svg 768w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Visao.svg 1024w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Visao.svg 450w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5be07c0\" data-id=\"5be07c0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af57376 elementor-widget elementor-widget-heading\" data-id=\"af57376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Visi\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74dc290 elementor-widget elementor-widget-text-editor\" data-id=\"74dc290\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ser reconocidos como una empresa innovadora que transformar\u00e1 la construcci\u00f3n tradicional en una industria eficiente y de alta productividad, a trav\u00e9s de Soluciones de Construcci\u00f3n Modular Inteligente, generando procesos, sistemas, proyectos y productos de alto desempe\u00f1o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50e9d50 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50e9d50\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5844236\" data-id=\"5844236\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0c849f elementor-widget elementor-widget-heading\" data-id=\"f0c849f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Valores<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcbff62 elementor-widget elementor-widget-text-editor\" data-id=\"bcbff62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8211; Responsabilidad ambiental y respeto por las personas;<\/p><p>&#8211; \u00c9tica y transparencia;<\/p><p>&#8211; Desarrollamos nuestros procesos y productos con la perspectiva del Cliente;<\/p><p>&#8211; Nuestro principal activo es el capital humano: valoramos el esp\u00edritu empresarial, el trabajo en equipo, la claridad en la comunicaci\u00f3n, el sentido de pertenencia y la proactividad;<\/p><p>&#8211; Somos agentes de cambio. Nos anticipamos a las tendencias y nos comprometemos con la tecnolog\u00eda y la innovaci\u00f3n, que son el motor de<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cc25a70\" data-id=\"cc25a70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-762f7e0 elementor-widget elementor-widget-image\" data-id=\"762f7e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2020\/12\/Valores.svg\" class=\"attachment-large size-large wp-image-135\" alt=\"\" srcset=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Valores.svg 150w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Valores.svg 300w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Valores.svg 768w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Valores.svg 1024w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Valores.svg 450w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-561c777c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"561c777c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74dd3d00\" data-id=\"74dd3d00\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b236b17 aux-appear-watch-animation aux-scale-down elementor-widget elementor-widget-aux_modern_heading\" data-id=\"b236b17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\"><\/h2><div class=\"aux-modern-heading-description\"><p><strong>La palabra ARATAU proviene del maor\u00ed \u201cmodular\u201d y fue elegida no solo por su significado y sonido, sino tambi\u00e9n por su afinidad con el tupi-guaran\u00ed. Nacimos como una empresa brasile\u00f1a fuerte, por eso los colores verde y amarillo.<\/strong><\/p><\/div><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-daaa043 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"daaa043\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b95f6ac\" data-id=\"b95f6ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0d1875 aux-appear-watch-animation aux-fade-in-up elementor-widget elementor-widget-aux_modern_heading\" data-id=\"c0d1875\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\"><\/h2><h3 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-before\">World-class team<\/span><\/h3><div class=\"aux-modern-heading-divider\"><\/div><div class=\"aux-modern-heading-description\"><p>Cultura orientada a resultados |\u00a0Business Intelligence |\u00a0Tecnolog\u00eda e Innovaci\u00f3n<\/p><\/div><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-303144f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"303144f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4a1de21\" data-id=\"4a1de21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21cce176 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"21cce176\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/Paulo.jpg\" title=\"Paulo\" alt=\"Paulo\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Paulo Oliveira <\/h3><p class=\"elementor-image-box-description\">Ceo<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-94b3e18\" data-id=\"94b3e18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7f5c16 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a7f5c16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2025\/05\/marcos.jpg\" title=\"marcos\" alt=\"marcos\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Marcos Hesketh<\/h3><p class=\"elementor-image-box-description\">DIRECTOR DE INGENIER\u00cdA<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b1fcaed\" data-id=\"b1fcaed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d210636 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d210636\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/Uira-Falseti.jpg\" title=\"Uir\u00e1 Falseti\" alt=\"Uir\u00e1 Falseti\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Uir\u00e1 Falseti <\/h3><p class=\"elementor-image-box-description\">DIRECTOR DE TECNOLOG\u00cdA E INNOVACI\u00d3N<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e91988d\" data-id=\"e91988d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cccdde elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0cccdde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/Alexandre-Pandolfo.jpg\" title=\"Alexandre Pandolfo\" alt=\"Alexandre Pandolfo\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Alexandre Pandolfo <\/h3><p class=\"elementor-image-box-description\">DIRECTOR DE DESARROLLO DE NEGOCIOS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18752b9 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18752b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-efd15f9\" data-id=\"efd15f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfa08a5 elementor-widget elementor-widget-heading\" data-id=\"dfa08a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sostenibilidad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a736eb elementor-widget elementor-widget-text-editor\" data-id=\"6a736eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Desde el concepto hasta el proceso de fabricaci\u00f3n y montaje, pensando en el cliente y contemplando el ciclo de vida del producto<\/strong><\/p><p>ARATAU desarrolla y entrega soluciones sostenibles, dise\u00f1adas para ser econ\u00f3micamente viables, que incluyen:<br \/>Reducci\u00f3n significativa de desperdicios y doble trabajo<br \/>Menor consumo de agua y energ\u00eda en la producci\u00f3n off-site<\/p><p>Eficiencia hidroenerg\u00e9tica<br \/>Reutilizaci\u00f3n de agua y sistemas de calefacci\u00f3n solar en todos los productos<br \/>Menos ruido y generaci\u00f3n de polvo en el lugar de la construcci\u00f3n &#8211; montaje de operaci\u00f3n (off-site)<br \/>Infraestructura para energ\u00eda fotovoltaica, automatizaci\u00f3n y climatizaci\u00f3n.<br \/>Mantenimiento r\u00e1pido y funcional &#8211; \u2013\u00a0shafts\u00a0y canales externos, sin instalaciones empotradas en hormig\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dbdf30d\" data-id=\"dbdf30d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-446b0e9 elementor-widget elementor-widget-image\" data-id=\"446b0e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2020\/12\/Edificacoes-Sustentaveis.svg\" class=\"attachment-large size-large wp-image-142\" alt=\"\" srcset=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Edificacoes-Sustentaveis.svg 150w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Edificacoes-Sustentaveis.svg 300w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Edificacoes-Sustentaveis.svg 768w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Edificacoes-Sustentaveis.svg 1024w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Edificacoes-Sustentaveis.svg 450w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad2b624 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad2b624\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3e360ab\" data-id=\"3e360ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0e5019 elementor-widget elementor-widget-image\" data-id=\"d0e5019\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2020\/12\/Tecnologia.svg\" class=\"attachment-large size-large wp-image-134\" alt=\"\" srcset=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Tecnologia.svg 150w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Tecnologia.svg 300w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Tecnologia.svg 768w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Tecnologia.svg 1024w, https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/\/2020\/12\/Tecnologia.svg 450w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-729805f\" data-id=\"729805f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45a2793 elementor-widget elementor-widget-heading\" data-id=\"45a2793\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Capital humano<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26714e2 elementor-widget elementor-widget-text-editor\" data-id=\"26714e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_column et_pb_column_1_3 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_text et_pb_text_0 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p>En un mundo centrado en tecnolog\u00eda, innovaci\u00f3n y transformaci\u00f3n digital, tan relevantes para el \u00e9xito de nuestro negocio, tener talento es fundamental. EL CAPITAL HUMANO ser\u00e1 siempre nuestro principal activo<\/p><\/div><\/div><\/div><div class=\"et_pb_column et_pb_column_1_3 et_pb_column_3 et_pb_css_mix_blend_mode_passthrough et-last-child\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Acerca de In\u00edcio Conoce la historia de ARATAU ARATAU &#8211; Construcci\u00f3n Modular es una empresa joven, pero nace con una enorme experiencia, sumando capacidades multidisciplinares en el sector de ingenier\u00eda, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/page-builder-content.php","meta":{"footnotes":""},"class_list":["post-3109","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acerca de - ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arataumodular.com\/app\/acerca-de\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acerca de - ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Acerca de In\u00edcio Conoce la historia de ARATAU ARATAU &#8211; Construcci\u00f3n Modular es una empresa joven, pero nace con una enorme experiencia, sumando capacidades multidisciplinares en el sector de ingenier\u00eda, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arataumodular.com\/app\/acerca-de\/\" \/>\n<meta property=\"og:site_name\" content=\"ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T15:46:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/modulares-784x700.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/acerca-de\\\/\",\"url\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/acerca-de\\\/\",\"name\":\"Acerca de - ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/acerca-de\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/acerca-de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/modulares-784x700.jpg\",\"datePublished\":\"2021-03-08T13:18:46+00:00\",\"dateModified\":\"2025-05-21T15:46:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/acerca-de\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/acerca-de\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/acerca-de\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/modulares.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/modulares.jpg\",\"width\":1561,\"height\":1010},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/acerca-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acerca de\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/#website\",\"url\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/\",\"name\":\"ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o\",\"description\":\"A Aratau Constru\u00e7\u00e3o Modular \u00e9 uma empresa inovadora, com solu\u00e7\u00f5es inteligentes de pr\u00e9-constru\u00e7\u00e3o e de constru\u00e7\u00e3o modular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/#organization\",\"name\":\"ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-aratau.svg\",\"contentUrl\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-aratau.svg\",\"width\":1000,\"height\":448,\"caption\":\"ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arataumodular.com\\\/app\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acerca de - ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arataumodular.com\/app\/acerca-de\/","og_locale":"pt_BR","og_type":"article","og_title":"Acerca de - ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o","og_description":"Acerca de In\u00edcio Conoce la historia de ARATAU ARATAU &#8211; Construcci\u00f3n Modular es una empresa joven, pero nace con una enorme experiencia, sumando capacidades multidisciplinares en el sector de ingenier\u00eda, [&hellip;]","og_url":"https:\/\/www.arataumodular.com\/app\/acerca-de\/","og_site_name":"ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o","article_modified_time":"2025-05-21T15:46:00+00:00","og_image":[{"url":"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/modulares-784x700.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arataumodular.com\/app\/acerca-de\/","url":"https:\/\/www.arataumodular.com\/app\/acerca-de\/","name":"Acerca de - ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.arataumodular.com\/app\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arataumodular.com\/app\/acerca-de\/#primaryimage"},"image":{"@id":"https:\/\/www.arataumodular.com\/app\/acerca-de\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/modulares-784x700.jpg","datePublished":"2021-03-08T13:18:46+00:00","dateModified":"2025-05-21T15:46:00+00:00","breadcrumb":{"@id":"https:\/\/www.arataumodular.com\/app\/acerca-de\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arataumodular.com\/app\/acerca-de\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.arataumodular.com\/app\/acerca-de\/#primaryimage","url":"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/modulares.jpg","contentUrl":"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2021\/01\/modulares.jpg","width":1561,"height":1010},{"@type":"BreadcrumbList","@id":"https:\/\/www.arataumodular.com\/app\/acerca-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.arataumodular.com\/app\/"},{"@type":"ListItem","position":2,"name":"Acerca de"}]},{"@type":"WebSite","@id":"https:\/\/www.arataumodular.com\/app\/#website","url":"https:\/\/www.arataumodular.com\/app\/","name":"ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o","description":"A Aratau Constru\u00e7\u00e3o Modular \u00e9 uma empresa inovadora, com solu\u00e7\u00f5es inteligentes de pr\u00e9-constru\u00e7\u00e3o e de constru\u00e7\u00e3o modular","publisher":{"@id":"https:\/\/www.arataumodular.com\/app\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arataumodular.com\/app\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.arataumodular.com\/app\/#organization","name":"ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o","url":"https:\/\/www.arataumodular.com\/app\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.arataumodular.com\/app\/#\/schema\/logo\/image\/","url":"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2020\/12\/logo-aratau.svg","contentUrl":"https:\/\/www.arataumodular.com\/app\/wp-content\/uploads\/2020\/12\/logo-aratau.svg","width":1000,"height":448,"caption":"ARATAU Constru\u00e7\u00e3o Modular \u2013 Constru\u00e7\u00e3o Modular e Servi\u00e7os de Pr\u00e9-Constru\u00e7\u00e3o"},"image":{"@id":"https:\/\/www.arataumodular.com\/app\/#\/schema\/logo\/image\/"}}]}},"blog_post_layout_featured_media_urls":{"thumbnail":"","full":""},"categories_names":null,"comments_number":"0","_links":{"self":[{"href":"https:\/\/www.arataumodular.com\/app\/wp-json\/wp\/v2\/pages\/3109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arataumodular.com\/app\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.arataumodular.com\/app\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.arataumodular.com\/app\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arataumodular.com\/app\/wp-json\/wp\/v2\/comments?post=3109"}],"version-history":[{"count":28,"href":"https:\/\/www.arataumodular.com\/app\/wp-json\/wp\/v2\/pages\/3109\/revisions"}],"predecessor-version":[{"id":9347,"href":"https:\/\/www.arataumodular.com\/app\/wp-json\/wp\/v2\/pages\/3109\/revisions\/9347"}],"wp:attachment":[{"href":"https:\/\/www.arataumodular.com\/app\/wp-json\/wp\/v2\/media?parent=3109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}